{"id":5952,"date":"2026-01-29T10:18:57","date_gmt":"2026-01-29T08:18:57","guid":{"rendered":"https:\/\/www.seviclimb.cat\/projectess\/remodelacio-de-la-zona-del-sorral-a-lescola-ausias-march\/"},"modified":"2026-02-09T11:45:28","modified_gmt":"2026-02-09T09:45:28","slug":"remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march","status":"publish","type":"projectes","link":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/","title":{"rendered":"Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March"},"content":{"rendered":"<p>Sustituci\u00f3n de las maderas actuales del per\u00edmetro del arenal por troncos de acacia e instalaci\u00f3n de juego con canales y gr\u00faas y umbr\u00e1culos con velas que se pueden poner y quitar.<\/p>\n","protected":false},"featured_media":2251,"template":"","class_list":["post-5952","projectes","type-projectes","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March - Seviclimb<\/title>\n<meta name=\"description\" content=\"Descubre nuestro proyecto de Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March - Seviclimb\" \/>\n<meta property=\"og:description\" content=\"Descubre nuestro proyecto de Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/\" \/>\n<meta property=\"og:site_name\" content=\"Seviclimb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Seviclimb\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T09:45:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/03\/IMG-20220311-WA0019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\\\/\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\\\/\",\"name\":\"Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March - Seviclimb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG-20220311-WA0019.jpg\",\"datePublished\":\"2026-01-29T08:18:57+00:00\",\"dateModified\":\"2026-02-09T09:45:28+00:00\",\"description\":\"Descubre nuestro proyecto de Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG-20220311-WA0019.jpg\",\"contentUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/IMG-20220311-WA0019.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\",\"name\":\"Seviclimb\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#organization\",\"name\":\"Seviclimb\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logoseviclimb-color.png\",\"contentUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logoseviclimb-color.png\",\"width\":1920,\"height\":1280,\"caption\":\"Seviclimb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Seviclimb\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sevi_climb\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March - Seviclimb","description":"Descubre nuestro proyecto de Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/","og_locale":"es_ES","og_type":"article","og_title":"Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March - Seviclimb","og_description":"Descubre nuestro proyecto de Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March.","og_url":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/","og_site_name":"Seviclimb","article_publisher":"https:\/\/www.facebook.com\/Seviclimb\/","article_modified_time":"2026-02-09T09:45:28+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/03\/IMG-20220311-WA0019.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/","url":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/","name":"Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March - Seviclimb","isPartOf":{"@id":"https:\/\/www.seviclimb.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/#primaryimage"},"image":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/#primaryimage"},"thumbnailUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/03\/IMG-20220311-WA0019.jpg","datePublished":"2026-01-29T08:18:57+00:00","dateModified":"2026-02-09T09:45:28+00:00","description":"Descubre nuestro proyecto de Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March.","breadcrumb":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/#primaryimage","url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/03\/IMG-20220311-WA0019.jpg","contentUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/03\/IMG-20220311-WA0019.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-de-la-zona-del-arenal-en-la-escuela-ausias-march\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.seviclimb.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/www.seviclimb.cat\/es\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Remodelaci\u00f3n de la zona del arenal en la Escuela Ausi\u00e0s March"}]},{"@type":"WebSite","@id":"https:\/\/www.seviclimb.cat\/es\/#website","url":"https:\/\/www.seviclimb.cat\/es\/","name":"Seviclimb","description":"","publisher":{"@id":"https:\/\/www.seviclimb.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.seviclimb.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.seviclimb.cat\/es\/#organization","name":"Seviclimb","url":"https:\/\/www.seviclimb.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seviclimb.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2021\/08\/logoseviclimb-color.png","contentUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2021\/08\/logoseviclimb-color.png","width":1920,"height":1280,"caption":"Seviclimb"},"image":{"@id":"https:\/\/www.seviclimb.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Seviclimb\/","https:\/\/www.instagram.com\/sevi_climb\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/projectes\/5952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/projectes"}],"about":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/types\/projectes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/media\/2251"}],"wp:attachment":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/media?parent=5952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}