{"id":5950,"date":"2026-01-29T10:19:43","date_gmt":"2026-01-29T08:19:43","guid":{"rendered":"https:\/\/www.seviclimb.cat\/projectess\/remodelacio-completa-de-zones-de-joc-a-lescola-vallmanya\/"},"modified":"2026-02-09T11:45:15","modified_gmt":"2026-02-09T09:45:15","slug":"remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya","status":"publish","type":"projectes","link":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/","title":{"rendered":"Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya"},"content":{"rendered":"<p>Instalaci\u00f3n de\u00a0<strong>juego de agua hecho a medida<\/strong>, tambi\u00e9n de un\u00a0<strong>juego de arenal con gr\u00faas<\/strong> y canales y colocaci\u00f3n de\u00a0<strong>umbr\u00e1culos con velas<\/strong>.<\/p>\n<p>En el patio infantil ten\u00edan un desnivel con tobog\u00e1n, y les hemos reacondicionado todo colocando unas escaleras y dos rampas con roc\u00f3dromo y cuerda. Adem\u00e1s, les hemos puesto troncos a todo el per\u00edmetro del desnivel para aguantar el suelo.<\/p>\n","protected":false},"featured_media":2083,"template":"","class_list":["post-5950","projectes","type-projectes","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya - Seviclimb<\/title>\n<meta name=\"description\" content=\"Descubre nuestro proyecto de Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya - Seviclimb\" \/>\n<meta property=\"og:description\" content=\"Descubre nuestro proyecto de Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/\" \/>\n<meta property=\"og:site_name\" content=\"Seviclimb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Seviclimb\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T09:45:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/04\/GOPR0568-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\\\/\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\\\/\",\"name\":\"Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya - Seviclimb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GOPR0568-scaled.jpg\",\"datePublished\":\"2026-01-29T08:19:43+00:00\",\"dateModified\":\"2026-02-09T09:45:15+00:00\",\"description\":\"Descubre nuestro proyecto de Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GOPR0568-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GOPR0568-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"DCIM100GOPROGOPR0568.JPG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\",\"name\":\"Seviclimb\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#organization\",\"name\":\"Seviclimb\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logoseviclimb-color.png\",\"contentUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logoseviclimb-color.png\",\"width\":1920,\"height\":1280,\"caption\":\"Seviclimb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Seviclimb\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sevi_climb\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya - Seviclimb","description":"Descubre nuestro proyecto de Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/","og_locale":"es_ES","og_type":"article","og_title":"Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya - Seviclimb","og_description":"Descubre nuestro proyecto de Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya.","og_url":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/","og_site_name":"Seviclimb","article_publisher":"https:\/\/www.facebook.com\/Seviclimb\/","article_modified_time":"2026-02-09T09:45:15+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/04\/GOPR0568-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/","url":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/","name":"Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya - Seviclimb","isPartOf":{"@id":"https:\/\/www.seviclimb.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/#primaryimage"},"image":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/#primaryimage"},"thumbnailUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/04\/GOPR0568-scaled.jpg","datePublished":"2026-01-29T08:19:43+00:00","dateModified":"2026-02-09T09:45:15+00:00","description":"Descubre nuestro proyecto de Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya.","breadcrumb":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/#primaryimage","url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/04\/GOPR0568-scaled.jpg","contentUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/04\/GOPR0568-scaled.jpg","width":2560,"height":1920,"caption":"DCIM100GOPROGOPR0568.JPG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/remodelacion-completa-de-zonas-de-juego-en-la-escuela-vallmanya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.seviclimb.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/www.seviclimb.cat\/es\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Remodelaci\u00f3n completa de zonas de juego en la Escuela Vallmanya"}]},{"@type":"WebSite","@id":"https:\/\/www.seviclimb.cat\/es\/#website","url":"https:\/\/www.seviclimb.cat\/es\/","name":"Seviclimb","description":"","publisher":{"@id":"https:\/\/www.seviclimb.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.seviclimb.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.seviclimb.cat\/es\/#organization","name":"Seviclimb","url":"https:\/\/www.seviclimb.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seviclimb.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2021\/08\/logoseviclimb-color.png","contentUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2021\/08\/logoseviclimb-color.png","width":1920,"height":1280,"caption":"Seviclimb"},"image":{"@id":"https:\/\/www.seviclimb.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Seviclimb\/","https:\/\/www.instagram.com\/sevi_climb\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/projectes\/5950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/projectes"}],"about":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/types\/projectes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/media\/2083"}],"wp:attachment":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/media?parent=5950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}