{"id":5936,"date":"2026-01-29T10:29:24","date_gmt":"2026-01-29T08:29:24","guid":{"rendered":"https:\/\/www.seviclimb.cat\/projectess\/equipament-complet-del-pati-de-lescola-la-noguera\/"},"modified":"2026-02-09T11:43:34","modified_gmt":"2026-02-09T09:43:34","slug":"equipamiento-completo-del-patio-de-la-escuela-la-noguera","status":"publish","type":"projectes","link":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/","title":{"rendered":"Equipamiento completo del patio de la Escuela la Noguera"},"content":{"rendered":"<p>Hemos dise\u00f1ado un patio amplio donde se ha instalado un multijuego, columpio, \u00e1gora de troncos y arenal todo de madera de acacia, tambi\u00e9n hemos puesto un tobog\u00e1n y casita.<\/p>\n","protected":false},"featured_media":2781,"template":"","class_list":["post-5936","projectes","type-projectes","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Equipamiento completo del patio de la Escuela la Noguera - Seviclimb<\/title>\n<meta name=\"description\" content=\"Descubre nuestro proyecto de Equipamiento completo del patio de la Escuela la Noguera.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equipamiento completo del patio de la Escuela la Noguera - Seviclimb\" \/>\n<meta property=\"og:description\" content=\"Descubre nuestro proyecto de Equipamiento completo del patio de la Escuela la Noguera.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/\" \/>\n<meta property=\"og:site_name\" content=\"Seviclimb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Seviclimb\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T09:43:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/06\/1654241149715.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\\\/\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\\\/\",\"name\":\"Equipamiento completo del patio de la Escuela la Noguera - Seviclimb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/1654241149715.jpg\",\"datePublished\":\"2026-01-29T08:29:24+00:00\",\"dateModified\":\"2026-02-09T09:43:34+00:00\",\"description\":\"Descubre nuestro proyecto de Equipamiento completo del patio de la Escuela la Noguera.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/1654241149715.jpg\",\"contentUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/1654241149715.jpg\",\"width\":1500,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Equipamiento completo del patio de la Escuela la Noguera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\",\"name\":\"Seviclimb\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#organization\",\"name\":\"Seviclimb\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logoseviclimb-color.png\",\"contentUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logoseviclimb-color.png\",\"width\":1920,\"height\":1280,\"caption\":\"Seviclimb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Seviclimb\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sevi_climb\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equipamiento completo del patio de la Escuela la Noguera - Seviclimb","description":"Descubre nuestro proyecto de Equipamiento completo del patio de la Escuela la Noguera.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/","og_locale":"es_ES","og_type":"article","og_title":"Equipamiento completo del patio de la Escuela la Noguera - Seviclimb","og_description":"Descubre nuestro proyecto de Equipamiento completo del patio de la Escuela la Noguera.","og_url":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/","og_site_name":"Seviclimb","article_publisher":"https:\/\/www.facebook.com\/Seviclimb\/","article_modified_time":"2026-02-09T09:43:34+00:00","og_image":[{"width":1500,"height":2000,"url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/06\/1654241149715.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/","url":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/","name":"Equipamiento completo del patio de la Escuela la Noguera - Seviclimb","isPartOf":{"@id":"https:\/\/www.seviclimb.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/#primaryimage"},"image":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/06\/1654241149715.jpg","datePublished":"2026-01-29T08:29:24+00:00","dateModified":"2026-02-09T09:43:34+00:00","description":"Descubre nuestro proyecto de Equipamiento completo del patio de la Escuela la Noguera.","breadcrumb":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/#primaryimage","url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/06\/1654241149715.jpg","contentUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/06\/1654241149715.jpg","width":1500,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/equipamiento-completo-del-patio-de-la-escuela-la-noguera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.seviclimb.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/www.seviclimb.cat\/es\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Equipamiento completo del patio de la Escuela la Noguera"}]},{"@type":"WebSite","@id":"https:\/\/www.seviclimb.cat\/es\/#website","url":"https:\/\/www.seviclimb.cat\/es\/","name":"Seviclimb","description":"","publisher":{"@id":"https:\/\/www.seviclimb.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.seviclimb.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.seviclimb.cat\/es\/#organization","name":"Seviclimb","url":"https:\/\/www.seviclimb.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seviclimb.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2021\/08\/logoseviclimb-color.png","contentUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2021\/08\/logoseviclimb-color.png","width":1920,"height":1280,"caption":"Seviclimb"},"image":{"@id":"https:\/\/www.seviclimb.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Seviclimb\/","https:\/\/www.instagram.com\/sevi_climb\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/projectes\/5936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/projectes"}],"about":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/types\/projectes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/media\/2781"}],"wp:attachment":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/media?parent=5936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}