{"id":5915,"date":"2026-01-29T10:44:25","date_gmt":"2026-01-29T08:44:25","guid":{"rendered":"https:\/\/www.seviclimb.cat\/projectess\/ampliacio-de-la-zona-de-jocs-a-li-e-sant-jordi\/"},"modified":"2026-02-09T11:41:00","modified_gmt":"2026-02-09T09:41:00","slug":"ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi","status":"publish","type":"projectes","link":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/","title":{"rendered":"Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi"},"content":{"rendered":"<p>Instalaci\u00f3n de cocinitas, mesas y una zona de bancos para crear una \u00e1gora.<\/p>\n","protected":false},"featured_media":3253,"template":"","class_list":["post-5915","projectes","type-projectes","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi - Seviclimb<\/title>\n<meta name=\"description\" content=\"Descubre nuestro proyecto de Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi - Seviclimb\" \/>\n<meta property=\"og:description\" content=\"Descubre nuestro proyecto de Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/\" \/>\n<meta property=\"og:site_name\" content=\"Seviclimb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Seviclimb\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T09:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/09\/IMG-20220908-WA0001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1196\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\\\/\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\\\/\",\"name\":\"Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi - Seviclimb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220908-WA0001.jpg\",\"datePublished\":\"2026-01-29T08:44:25+00:00\",\"dateModified\":\"2026-02-09T09:41:00+00:00\",\"description\":\"Descubre nuestro proyecto de Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220908-WA0001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220908-WA0001.jpg\",\"width\":1600,\"height\":1196},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\",\"name\":\"Seviclimb\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#organization\",\"name\":\"Seviclimb\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logoseviclimb-color.png\",\"contentUrl\":\"https:\\\/\\\/www.seviclimb.cat\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logoseviclimb-color.png\",\"width\":1920,\"height\":1280,\"caption\":\"Seviclimb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seviclimb.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Seviclimb\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sevi_climb\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi - Seviclimb","description":"Descubre nuestro proyecto de Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/","og_locale":"es_ES","og_type":"article","og_title":"Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi - Seviclimb","og_description":"Descubre nuestro proyecto de Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi.","og_url":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/","og_site_name":"Seviclimb","article_publisher":"https:\/\/www.facebook.com\/Seviclimb\/","article_modified_time":"2026-02-09T09:41:00+00:00","og_image":[{"width":1600,"height":1196,"url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/09\/IMG-20220908-WA0001.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/","url":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/","name":"Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi - Seviclimb","isPartOf":{"@id":"https:\/\/www.seviclimb.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/#primaryimage"},"image":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/09\/IMG-20220908-WA0001.jpg","datePublished":"2026-01-29T08:44:25+00:00","dateModified":"2026-02-09T09:41:00+00:00","description":"Descubre nuestro proyecto de Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi.","breadcrumb":{"@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/#primaryimage","url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/09\/IMG-20220908-WA0001.jpg","contentUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2022\/09\/IMG-20220908-WA0001.jpg","width":1600,"height":1196},{"@type":"BreadcrumbList","@id":"https:\/\/www.seviclimb.cat\/es\/proyectos\/ampliacion-de-la-zona-de-juegos-en-el-li-e-sant-jordi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.seviclimb.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/www.seviclimb.cat\/es\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Ampliaci\u00f3n de la zona de juegos en el I.E. Sant Jordi"}]},{"@type":"WebSite","@id":"https:\/\/www.seviclimb.cat\/es\/#website","url":"https:\/\/www.seviclimb.cat\/es\/","name":"Seviclimb","description":"","publisher":{"@id":"https:\/\/www.seviclimb.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.seviclimb.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.seviclimb.cat\/es\/#organization","name":"Seviclimb","url":"https:\/\/www.seviclimb.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seviclimb.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2021\/08\/logoseviclimb-color.png","contentUrl":"https:\/\/www.seviclimb.cat\/wp-content\/uploads\/2021\/08\/logoseviclimb-color.png","width":1920,"height":1280,"caption":"Seviclimb"},"image":{"@id":"https:\/\/www.seviclimb.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Seviclimb\/","https:\/\/www.instagram.com\/sevi_climb\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/projectes\/5915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/projectes"}],"about":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/types\/projectes"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/media\/3253"}],"wp:attachment":[{"href":"https:\/\/www.seviclimb.cat\/es\/wp-json\/wp\/v2\/media?parent=5915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}